{"id":38620,"date":"2023-01-10T10:48:41","date_gmt":"2023-01-10T09:48:41","guid":{"rendered":"https:\/\/sublime-clinic.ch\/clinica\/"},"modified":"2026-06-23T13:52:10","modified_gmt":"2026-06-23T11:52:10","slug":"clinica","status":"publish","type":"page","link":"https:\/\/sublime-clinic.ch\/it\/clinica\/","title":{"rendered":"Le nostre cliniche partner"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"38620\" class=\"elementor elementor-38620 elementor-28876\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-455ef07 elementor-section-height-min-height elementor-section-items-stretch elementor-section-content-middle elementor-section-boxed elementor-section-height-default\" data-id=\"455ef07\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:38318,&quot;url&quot;:&quot;https:\\\/\\\/sublime-clinic.ch\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/medical-health-tool-in-surgical-operating-room-in-2021-12-09-06-49-06-utc.jpg&quot;},{&quot;id&quot;:38319,&quot;url&quot;:&quot;https:\\\/\\\/sublime-clinic.ch\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/woman-standing-at-reception-of-dental-clinic-2022-01-27-22-54-40-utc.jpg&quot;},{&quot;id&quot;:38320,&quot;url&quot;:&quot;https:\\\/\\\/sublime-clinic.ch\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/a-woman-has-a-dental-check-up-in-dentist-surgery-2021-08-27-17-58-25-utc.jpg&quot;}],&quot;background_slideshow_slide_duration&quot;:3000,&quot;background_slideshow_transition_duration&quot;:4000,&quot;background_slideshow_ken_burns&quot;:&quot;yes&quot;,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_ken_burns_zoom_direction&quot;:&quot;in&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-88cffd4\" data-id=\"88cffd4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6b19534 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6b19534\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-75ba9f2 animated-slow elementor-invisible\" data-id=\"75ba9f2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInDown&quot;,&quot;animation_delay&quot;:300}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a294764 elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"a294764\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Mzg3MzQsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">I nostri interventi<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15fdf68 elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"15fdf68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/sublime-clinic.ch\/it\/contatto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contatto<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-50e6bbc animated-slow elementor-align-center elementor-invisible elementor-widget elementor-widget-lottie\" data-id=\"50e6bbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;source&quot;:&quot;external_url&quot;,&quot;source_external_url&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/assets9.lottiefiles.com\\\/private_files\\\/lf30_ul7SjW.json&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;link_to&quot;:&quot;custom&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;play_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.8,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;fadeInDown&quot;,&quot;_animation_delay&quot;:500,&quot;custom_link&quot;:{&quot;url&quot;:&quot;#clinic&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;trigger&quot;:&quot;arriving_to_viewport&quot;,&quot;viewport&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;start_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;end_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:100,&quot;sizes&quot;:[]},&quot;renderer&quot;:&quot;svg&quot;}\" data-widget_type=\"lottie.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a class=\"e-lottie__container__link\" href=\"#clinic\"><div class=\"e-lottie__container\"><div class=\"e-lottie__animation\"><\/div><\/div><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1ce24be elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1ce24be\" data-element_type=\"section\" data-e-type=\"section\" id=\"clinic\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f52dcd7\" data-id=\"f52dcd7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a6ec0f elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"1a6ec0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d\u2019images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 di 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1a6ec0f\" data-elementor-lightbox-title=\"IMG_1003\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzg0ODgsInVybCI6Imh0dHBzOlwvXC9zdWJsaW1lLWNsaW5pYy5jaFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL0lNR18xMDAzLmpwZyIsInNsaWRlc2hvdyI6IjFhNmVjMGYifQ%3D%3D\" href=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/06\/IMG_1003.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/elementor\/thumbs\/IMG_1003-pqqw1zd0mwdv2f9ie9be5nlj4kc35mtenltcx0u2tg.jpg\" alt=\"IMG_1003\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 di 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1a6ec0f\" data-elementor-lightbox-title=\"IMG_1002\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzg0ODksInVybCI6Imh0dHBzOlwvXC9zdWJsaW1lLWNsaW5pYy5jaFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL0lNR18xMDAyLmpwZyIsInNsaWRlc2hvdyI6IjFhNmVjMGYifQ%3D%3D\" href=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/06\/IMG_1002.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/elementor\/thumbs\/IMG_1002-pqqw1fmendmuam26lis87akunh1dnzn1kw45u7ncg4.jpg\" alt=\"IMG_1002\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 di 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1a6ec0f\" data-elementor-lightbox-title=\"IMG_0997\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzg0OTAsInVybCI6Imh0dHBzOlwvXC9zdWJsaW1lLWNsaW5pYy5jaFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL0lNR18wOTk3LmpwZyIsInNsaWRlc2hvdyI6IjFhNmVjMGYifQ%3D%3D\" href=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/06\/IMG_0997.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/elementor\/thumbs\/IMG_0997-pqqw0ypb8czohmqrcbgxyeujyjcrtfrvikdf78cfk4.jpg\" alt=\"IMG_0997\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 di 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1a6ec0f\" data-elementor-lightbox-title=\"IMG_0994\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzg0OTEsInVybCI6Imh0dHBzOlwvXC9zdWJsaW1lLWNsaW5pYy5jaFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL0lNR18wOTk0LmpwZyIsInNsaWRlc2hvdyI6IjFhNmVjMGYifQ%3D%3D\" href=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/06\/IMG_0994.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/elementor\/thumbs\/IMG_0994-pqqw0d30v6632lm5uk4iv2ayaobbwee1rld95v8hj8.jpg\" alt=\"IMG_0994\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 di 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1a6ec0f\" data-elementor-lightbox-title=\"IMG_0992\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzg0OTIsInVybCI6Imh0dHBzOlwvXC9zdWJsaW1lLWNsaW5pYy5jaFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL0lNR18wOTkyLmpwZyIsInNsaWRlc2hvdyI6IjFhNmVjMGYifQ%3D%3D\" href=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/06\/IMG_0992.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/elementor\/thumbs\/IMG_0992-pqqvzx3rmzk7l89dfv7v6oc474i39jmm1ea005w6h0.jpg\" alt=\"IMG_0992\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 di 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1a6ec0f\" data-elementor-lightbox-title=\"IMG_0985\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzg0OTMsInVybCI6Imh0dHBzOlwvXC9zdWJsaW1lLWNsaW5pYy5jaFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL0lNR18wOTg1LmpwZyIsInNsaWRlc2hvdyI6IjFhNmVjMGYifQ%3D%3D\" href=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/06\/IMG_0985.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/elementor\/thumbs\/IMG_0985-pqqvz5ug4siw8jcyv1food7qyy8g2bme9ncx350lhg.jpg\" alt=\"IMG_0985\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 di 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1a6ec0f\" data-elementor-lightbox-title=\"IMG_0984\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzg0OTQsInVybCI6Imh0dHBzOlwvXC9zdWJsaW1lLWNsaW5pYy5jaFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL0lNR18wOTg0LmpwZyIsInNsaWRlc2hvdyI6IjFhNmVjMGYifQ%3D%3D\" href=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/06\/IMG_0984.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/elementor\/thumbs\/IMG_0984-pqqvyoxcprvqfk1jlu4efhhga0ju7rr87bm6g5polg.jpg\" alt=\"IMG_0984\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 di 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1a6ec0f\" data-elementor-lightbox-title=\"IMG_0981\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzg0OTUsInVybCI6Imh0dHBzOlwvXC9zdWJsaW1lLWNsaW5pYy5jaFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL0lNR18wOTgxLmpwZyIsInNsaWRlc2hvdyI6IjFhNmVjMGYifQ%3D%3D\" href=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/06\/IMG_0981.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/elementor\/thumbs\/IMG_0981-pqqvxzjpl8wzq32eq15h25w08m0xfxyh3u02horb9g.jpg\" alt=\"IMG_0981\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 di 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1a6ec0f\" data-elementor-lightbox-title=\"IMG_0982\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzg0OTYsInVybCI6Imh0dHBzOlwvXC9zdWJsaW1lLWNsaW5pYy5jaFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL0lNR18wOTgyLmpwZyIsInNsaWRlc2hvdyI6IjFhNmVjMGYifQ%3D%3D\" href=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/06\/IMG_0982.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/elementor\/thumbs\/IMG_0982-pqqvximm689tx3qzgtu6ta5pjocble3b1i9bupgedg.jpg\" alt=\"IMG_0982\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9337ee9 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"9337ee9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d\u2019images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 di 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9337ee9\" data-elementor-lightbox-title=\"Sublime Clinique - Installation\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzg0ODYsInVybCI6Imh0dHBzOlwvXC9zdWJsaW1lLWNsaW5pYy5jaFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL3N1YmxpbWUtY2xpbmljLXBob3RvLTE4LmpwZyIsInNsaWRlc2hvdyI6IjkzMzdlZTkifQ%3D%3D\" href=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/06\/sublime-clinic-photo-18.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/elementor\/thumbs\/sublime-clinic-photo-18-pprpmmdo5jde626dwuwlrkuro1rtpb5grhouxh7dxg.jpg\" alt=\"Sublime Clinique - Installation\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 di 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9337ee9\" data-elementor-lightbox-title=\"Sublime Clinique - Installation\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzg0NzksInVybCI6Imh0dHBzOlwvXC9zdWJsaW1lLWNsaW5pYy5jaFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL3N1YmxpbWUtY2xpbmljLXBob3RvLTExLmpwZyIsInNsaWRlc2hvdyI6IjkzMzdlZTkifQ%3D%3D\" href=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/06\/sublime-clinic-photo-11.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/elementor\/thumbs\/sublime-clinic-photo-11-pqqw6f5kscl0rzqggw63kmz21pvqrlbblqt637uxc4.jpg\" alt=\"Sublime Clinique - Installation\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 di 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9337ee9\" data-elementor-lightbox-title=\"Sublime Clinique - Installation\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzg0ODMsInVybCI6Imh0dHBzOlwvXC9zdWJsaW1lLWNsaW5pYy5jaFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL3N1YmxpbWUtY2xpbmljLXBob3RvLTE1LmpwZyIsInNsaWRlc2hvdyI6IjkzMzdlZTkifQ%3D%3D\" href=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/06\/sublime-clinic-photo-15.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/elementor\/thumbs\/sublime-clinic-photo-15-pqqw4gnojrwil8kuwjp2vmrhhtj7qajgc1vr3grgas.jpg\" alt=\"Sublime Clinique - Installation\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 di 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9337ee9\" data-elementor-lightbox-title=\"Sublime Clinique - Installation\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzg0ODAsInVybCI6Imh0dHBzOlwvXC9zdWJsaW1lLWNsaW5pYy5jaFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL3N1YmxpbWUtY2xpbmljLXBob3RvLTEyLmpwZyIsInNsaWRlc2hvdyI6IjkzMzdlZTkifQ%3D%3D\" href=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/06\/sublime-clinic-photo-12.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/elementor\/thumbs\/sublime-clinic-photo-12-pqqw5slg8bq51cn84mf1wsnzsgyxmutrin5ikksdhg.jpg\" alt=\"Sublime Clinique - Installation\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 di 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9337ee9\" data-elementor-lightbox-title=\"Sublime Clinique - Installation\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzg0NzMsInVybCI6Imh0dHBzOlwvXC9zdWJsaW1lLWNsaW5pYy5jaFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL3N1YmxpbWUtY2xpbmljLXBob3RvLTUuanBnIiwic2xpZGVzaG93IjoiOTMzN2VlOSJ9\" href=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/06\/sublime-clinic-photo-5.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/elementor\/thumbs\/sublime-clinic-photo-5-pqqw9bhnuyjukpiwjn9oren7zhlhhztj0382cxk85g.jpg\" alt=\"Sublime Clinique - Installation\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 di 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9337ee9\" data-elementor-lightbox-title=\"Sublime Clinique - Installation\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzg0NzUsInVybCI6Imh0dHBzOlwvXC9zdWJsaW1lLWNsaW5pYy5jaFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL3N1YmxpbWUtY2xpbmljLXBob3RvLTcuanBnIiwic2xpZGVzaG93IjoiOTMzN2VlOSJ9\" href=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/06\/sublime-clinic-photo-7.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/elementor\/thumbs\/sublime-clinic-photo-7-pqqw8dnh0x9iyqw218n49n6mlm89sw36vfql2yyedg.jpg\" alt=\"Sublime Clinique - Installation\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 di 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9337ee9\" data-elementor-lightbox-title=\"Sublime Clinique - Installation\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzg0NzIsInVybCI6Imh0dHBzOlwvXC9zdWJsaW1lLWNsaW5pYy5jaFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL3N1YmxpbWUtY2xpbmljLXBob3RvLTQuanBnIiwic2xpZGVzaG93IjoiOTMzN2VlOSJ9\" href=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/06\/sublime-clinic-photo-4.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/elementor\/thumbs\/sublime-clinic-photo-4-pqqw9y1sezeqbcm4vx0qf8ya8qiamqb336vpvkms04.jpg\" alt=\"Sublime Clinique - Installation\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 di 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9337ee9\" data-elementor-lightbox-title=\"Sublime Clinique - Installation\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzg0NzEsInVybCI6Imh0dHBzOlwvXC9zdWJsaW1lLWNsaW5pYy5jaFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL3N1YmxpbWUtY2xpbmljLXBob3RvLTMuanBnIiwic2xpZGVzaG93IjoiOTMzN2VlOSJ9\" href=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/06\/sublime-clinic-photo-3.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/elementor\/thumbs\/sublime-clinic-photo-3-pqqwaeyvu01w4bxk54c0o4okxo6wha695imgijxow4.jpg\" alt=\"Sublime Clinique - Installation\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 di 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9337ee9\" data-elementor-lightbox-title=\"Sublime Clinique - Installation\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzg0ODEsInVybCI6Imh0dHBzOlwvXC9zdWJsaW1lLWNsaW5pYy5jaFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL3N1YmxpbWUtY2xpbmljLXBob3RvLTEzLmpwZyIsInNsaWRlc2hvdyI6IjkzMzdlZTkifQ%3D%3D\" href=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/06\/sublime-clinic-photo-13.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/elementor\/thumbs\/sublime-clinic-photo-13-pqqw5cm70549jzafpxie8ep5ox5p002bsg29evg2f8.jpg\" alt=\"Sublime Clinique - Installation\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 di 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9337ee9\" data-elementor-lightbox-title=\"Sublime Clinique - Installation\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzg0ODIsInVybCI6Imh0dHBzOlwvXC9zdWJsaW1lLWNsaW5pYy5jaFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL3N1YmxpbWUtY2xpbmljLXBob3RvLTE0LmpwZyIsInNsaWRlc2hvdyI6IjkzMzdlZTkifQ%3D%3D\" href=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/06\/sublime-clinic-photo-14.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/elementor\/thumbs\/sublime-clinic-photo-14-pqqw4wmxryie2lxnb8lqk0qbldcgd5aw28z0963rd0.jpg\" alt=\"Sublime Clinique - Installation\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 di 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9337ee9\" data-elementor-lightbox-title=\"Sublime Clinique - Installation\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzg0ODQsInVybCI6Imh0dHBzOlwvXC9zdWJsaW1lLWNsaW5pYy5jaFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL3N1YmxpbWUtY2xpbmljLXBob3RvLTE2LmpwZyIsInNsaWRlc2hvdyI6IjkzMzdlZTkifQ%3D%3D\" href=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/06\/sublime-clinic-photo-16.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/elementor\/thumbs\/sublime-clinic-photo-16-pqqw3v1e6l2x67g9escnsa7vtyhrt95ml2vl23ni9w.jpg\" alt=\"Sublime Clinique - Installation\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 di 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9337ee9\" data-elementor-lightbox-title=\"Sublime Clinique - Installation\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzg0ODUsInVybCI6Imh0dHBzOlwvXC9zdWJsaW1lLWNsaW5pYy5jaFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL3N1YmxpbWUtY2xpbmljLXBob3RvLTE3LmpwZyIsInNsaWRlc2hvdyI6IjkzMzdlZTkifQ%3D%3D\" href=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/06\/sublime-clinic-photo-17.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/elementor\/thumbs\/sublime-clinic-photo-17-pqqw3fzz58ic0g23ulumoe0ibsjwe3hx70ftdo9t1g.jpg\" alt=\"Sublime Clinique - Installation\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 di 13\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9337ee9\" data-elementor-lightbox-title=\"Sublime Clinique - Installation\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzg0ODcsInVybCI6Imh0dHBzOlwvXC9zdWJsaW1lLWNsaW5pYy5jaFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL3N1YmxpbWUtY2xpbmljLXBob3RvLTE5LmpwZyIsInNsaWRlc2hvdyI6IjkzMzdlZTkifQ%3D%3D\" href=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/06\/sublime-clinic-photo-19.jpg\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/elementor\/thumbs\/sublime-clinic-photo-19-pqqw2i5sb780ehf9c7826mjwxx6oozrl2cyc3pnz9g.jpg\" alt=\"Sublime Clinique - Installation\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5737246\" data-id=\"5737246\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35f4c8c elementor-widget elementor-widget-heading\" data-id=\"35f4c8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Cliniche<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc21975 elementor-widget elementor-widget-heading\" data-id=\"cc21975\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le nostre cliniche partner<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-640afc6 elementor-widget elementor-widget-text-editor\" data-id=\"640afc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In qualit\u00e0 di azienda svizzera specializzata in turismo medico, collaboriamo in esclusiva con due delle cliniche pi\u00f9 rinomate della Turchia.<\/p><p>  Con oltre 55.000 metri quadrati di spazio interno, il nostro ospedale partner \u00e8 alto 19 piani e pu\u00f2 ospitare 450 letti. Tra le 16 sale operatorie ve ne sono 2 completamente attrezzate con tecnologia di sala operatoria ibrida. Molto rinomata in Turchia, la nostra clinica partner mira a continuare a crescere a livello nazionale e internazionale.  <\/p><p>Per le vostre cure dentali, siamo orgogliosi di collaborare con la pi\u00f9 prestigiosa clinica dentale della Turchia. La clinica \u00e8 dotata delle pi\u00f9 moderne tecnologie e fornisce trattamenti di qualit\u00e0 eccellente da parte di un team di dentisti e specialisti altamente qualificati. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9ea499 elementor-widget elementor-widget-button\" data-id=\"b9ea499\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJ0eXBlIjoidmlkZW8iLCJ2aWRlb1R5cGUiOiJob3N0ZWQiLCJ1cmwiOiJodHRwczpcL1wvcmVzLmNsb3VkaW5hcnkuY29tXC90dXJtYWxpbnNyYmlqYVwvdmlkZW9cL3VwbG9hZFwvdjE2NTI5NTk0NDVcL1Vwd29ya1wvV2hhdHNBcHBfVmlkZW9fMjAyMi0wNS0xMF9hdF8xOS4xNy4wMF9ydHg1a2subXA0In0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-play-circle\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Per saperne di pi\u00f9 sulle nostre cliniche<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-83cc37a elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"83cc37a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b2d30e3\" data-id=\"b2d30e3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eda3e38 elementor-widget elementor-widget-heading\" data-id=\"eda3e38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Perch\u00e9?<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-820ef9a elementor-widget elementor-widget-heading\" data-id=\"820ef9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sublime Clinique: la nostra esperienza al vostro servizio<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-183e4be elementor-widget elementor-widget-text-editor\" data-id=\"183e4be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le nostre vacanze di bellezza all-inclusive vi permetteranno di realizzare il vostro sogno in tutta serenit\u00e0. Vi assicuriamo una selezione delle migliori cliniche con le tecnologie pi\u00f9 avanzate. Ci occupiamo di tutto per garantire che il vostro viaggio si svolga senza intoppi e a costi contenuti.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2a2a350 animated-slow elementor-invisible\" data-id=\"2a2a350\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dbab20b elementor-widget elementor-widget-counter\" data-id=\"dbab20b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">operazioni di successo<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"50000\" data-from-value=\"0\" data-delimiter=\" \">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">+<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fb1a8e7 elementor-section-content-middle elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fb1a8e7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-dbbe3ef\" data-id=\"dbbe3ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-09cf2d3 elementor-widget elementor-widget-heading\" data-id=\"09cf2d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Clinica certificata<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d7a9c72 elementor-widget elementor-widget-image\" data-id=\"d7a9c72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/04\/diploma-scroll-close-up-2022-02-09-19-28-06-utc-1024x683.jpg\" class=\"elementor-animation-float attachment-large size-large wp-image-38322\" alt=\"\" srcset=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/04\/diploma-scroll-close-up-2022-02-09-19-28-06-utc-1024x683.jpg 1024w, https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/04\/diploma-scroll-close-up-2022-02-09-19-28-06-utc-300x200.jpg 300w, https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/04\/diploma-scroll-close-up-2022-02-09-19-28-06-utc-768x512.jpg 768w, https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/04\/diploma-scroll-close-up-2022-02-09-19-28-06-utc-1536x1024.jpg 1536w, https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/04\/diploma-scroll-close-up-2022-02-09-19-28-06-utc.jpg 1920w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e13a9fc elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"e13a9fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/sublime-clinic.ch\/it\/contatto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Richiedi un preventivo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8bc3aec\" data-id=\"8bc3aec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-223f233 elementor-widget elementor-widget-heading\" data-id=\"223f233\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Scoprire<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4eaa89c elementor-widget elementor-widget-heading\" data-id=\"4eaa89c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">I nostri punti di forza<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-206bd16 elementor-widget elementor-widget-text-editor\" data-id=\"206bd16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Clinica Sublime, <strong>LA<\/strong> specialista in chirurgia plastica in Turchia<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-589f20b elementor-widget elementor-widget-progress\" data-id=\"589f20b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"progress.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<span class=\"elementor-title\" id=\"elementor-progress-bar-589f20b\">\n\t\t\t\tAttrezzature all'avanguardia\t\t\t<\/span>\n\t\t\n\t\t<div aria-labelledby=\"elementor-progress-bar-589f20b\" class=\"elementor-progress-wrapper\" role=\"progressbar\" aria-valuemin=\"0\" aria-valuemax=\"100\" aria-valuenow=\"90\">\n\t\t\t<div class=\"elementor-progress-bar\" data-max=\"90\">\n\t\t\t\t<span class=\"elementor-progress-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-progress-percentage\">90%<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c17ba73 elementor-widget elementor-widget-progress\" data-id=\"c17ba73\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"progress.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<span class=\"elementor-title\" id=\"elementor-progress-bar-c17ba73\">\n\t\t\t\tPrezzi competitivi\t\t\t<\/span>\n\t\t\n\t\t<div aria-labelledby=\"elementor-progress-bar-c17ba73\" class=\"elementor-progress-wrapper\" role=\"progressbar\" aria-valuemin=\"0\" aria-valuemax=\"100\" aria-valuenow=\"95\">\n\t\t\t<div class=\"elementor-progress-bar\" data-max=\"95\">\n\t\t\t\t<span class=\"elementor-progress-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-progress-percentage\">95%<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61ac5f4 elementor-widget elementor-widget-progress\" data-id=\"61ac5f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"progress.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<span class=\"elementor-title\" id=\"elementor-progress-bar-61ac5f4\">\n\t\t\t\tChirurghi esperti\t\t\t<\/span>\n\t\t\n\t\t<div aria-labelledby=\"elementor-progress-bar-61ac5f4\" class=\"elementor-progress-wrapper\" role=\"progressbar\" aria-valuemin=\"0\" aria-valuemax=\"100\" aria-valuenow=\"100\">\n\t\t\t<div class=\"elementor-progress-bar\" data-max=\"100\">\n\t\t\t\t<span class=\"elementor-progress-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-progress-percentage\">100%<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a5e2cfe elementor-widget elementor-widget-progress\" data-id=\"a5e2cfe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"progress.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<span class=\"elementor-title\" id=\"elementor-progress-bar-a5e2cfe\">\n\t\t\t\tCliniche standard internazionali\t\t\t<\/span>\n\t\t\n\t\t<div aria-labelledby=\"elementor-progress-bar-a5e2cfe\" class=\"elementor-progress-wrapper\" role=\"progressbar\" aria-valuemin=\"0\" aria-valuemax=\"100\" aria-valuenow=\"99\">\n\t\t\t<div class=\"elementor-progress-bar\" data-max=\"99\">\n\t\t\t\t<span class=\"elementor-progress-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-progress-percentage\">99%<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7bf38c5 elementor-widget elementor-widget-progress\" data-id=\"7bf38c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"progress.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<span class=\"elementor-title\" id=\"elementor-progress-bar-7bf38c5\">\n\t\t\t\t  Competenza\t\t\t<\/span>\n\t\t\n\t\t<div aria-labelledby=\"elementor-progress-bar-7bf38c5\" class=\"elementor-progress-wrapper\" role=\"progressbar\" aria-valuemin=\"0\" aria-valuemax=\"100\" aria-valuenow=\"98\">\n\t\t\t<div class=\"elementor-progress-bar\" data-max=\"98\">\n\t\t\t\t<span class=\"elementor-progress-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-progress-percentage\">98%<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c189e1a elementor-section-content-middle elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c189e1a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-62b7ea9\" data-id=\"62b7ea9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-04ad854 elementor-widget elementor-widget-heading\" data-id=\"04ad854\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Squadra<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a0b76f elementor-widget elementor-widget-heading\" data-id=\"1a0b76f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Scoprite i nostri chirurghi esperti<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a0e6c21 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"a0e6c21\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d78a9b9\" data-id=\"d78a9b9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eb9ec07 elementor-widget elementor-widget-image\" data-id=\"eb9ec07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"362\" src=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/04\/Dr.-Cengizhan-pic.jpg\" class=\"attachment-full size-full wp-image-38417\" alt=\"\" srcset=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/04\/Dr.-Cengizhan-pic.jpg 400w, https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/04\/Dr.-Cengizhan-pic-300x272.jpg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2c5541 elementor-widget elementor-widget-heading\" data-id=\"d2c5541\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">I dott. Cengizhan Ek\u0131zcel\u0131 <\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1cbc780 elementor-widget elementor-widget-heading\" data-id=\"1cbc780\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Chirurgia plastica estetica e ricostruttiva<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4027f14 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4027f14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a9f43f elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"1a9f43f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Mzg3MTksInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Formazione ed esperienza<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-07fc1ae\" data-id=\"07fc1ae\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a0a1d0d elementor-widget elementor-widget-image\" data-id=\"a0a1d0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"362\" src=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/04\/Dr-Taha-pic.jpg\" class=\"attachment-large size-large wp-image-38416\" alt=\"\" srcset=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/04\/Dr-Taha-pic.jpg 400w, https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/04\/Dr-Taha-pic-300x272.jpg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81b7d99 elementor-widget elementor-widget-heading\" data-id=\"81b7d99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Dott. Taha S\u00d6NMEZ<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0fcabd2 elementor-widget elementor-widget-heading\" data-id=\"0fcabd2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Chirurgia plastica estetica e ricostruttiva<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-420f9ea elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"420f9ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cec958b elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"cec958b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Mzg3MzMsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">formazione ed esperienza<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-68a35cd\" data-id=\"68a35cd\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb4e666 elementor-widget elementor-widget-image\" data-id=\"cb4e666\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"362\" src=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/04\/Dr-Alperen-pic..jpg\" class=\"attachment-large size-large wp-image-38415\" alt=\"\" srcset=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/04\/Dr-Alperen-pic..jpg 400w, https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/04\/Dr-Alperen-pic.-300x272.jpg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e511923 elementor-widget elementor-widget-heading\" data-id=\"e511923\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Dott. Alperen TEK\u0130N<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-787cb30 elementor-widget elementor-widget-heading\" data-id=\"787cb30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Chirurgia plastica estetica e ricostruttiva<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f3b1a6 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6f3b1a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe003b1 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"fe003b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Mzg3NDAsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Formazione ed esperienza<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-30f97a8 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"30f97a8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4614a72\" data-id=\"4614a72\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7bb2b21 elementor-widget elementor-widget-image\" data-id=\"7bb2b21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"640\" src=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2026\/06\/sublime-dr-photo-1024x819.png\" class=\"attachment-large size-large wp-image-45907\" alt=\"\" srcset=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2026\/06\/sublime-dr-photo-1024x819.png 1024w, https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2026\/06\/sublime-dr-photo-300x240.png 300w, https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2026\/06\/sublime-dr-photo-768x615.png 768w, https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2026\/06\/sublime-dr-photo.png 1402w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d06263d elementor-widget elementor-widget-heading\" data-id=\"d06263d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Dott. Abdullah S\u00dcR\u00dcC\u00dc<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f5473c elementor-widget elementor-widget-heading\" data-id=\"4f5473c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Chirurgia plastica estetica e ricostruttiva<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d901688 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d901688\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-990be24 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"990be24\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Mzg3MjMsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">formazione ed esperienza<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-868a9d8\" data-id=\"868a9d8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f8e4544 elementor-widget elementor-widget-image\" data-id=\"f8e4544\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"310\" height=\"320\" src=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/06\/photo-ophtalmo.png\" class=\"attachment-large size-large wp-image-38540\" alt=\"\" srcset=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/06\/photo-ophtalmo.png 310w, https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/06\/photo-ophtalmo-291x300.png 291w\" sizes=\"(max-width: 310px) 100vw, 310px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e8437c elementor-widget elementor-widget-heading\" data-id=\"9e8437c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">I dott. Muhammed Hatipo\u011flu <\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d230ab elementor-widget elementor-widget-heading\" data-id=\"3d230ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Oftalmologo  <br> <\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be447c3 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"be447c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3967b67 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"3967b67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Mzg3MjAsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Formazione ed esperienza<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-350087a\" data-id=\"350087a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f57c6af elementor-widget elementor-widget-image\" data-id=\"f57c6af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/06\/Photo-Sarkan-683x1024.jpg\" class=\"attachment-large size-large wp-image-38541\" alt=\"\" srcset=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/06\/Photo-Sarkan-683x1024.jpg 683w, https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/06\/Photo-Sarkan-200x300.jpg 200w, https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/06\/Photo-Sarkan-768x1152.jpg 768w, https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/06\/Photo-Sarkan-1024x1536.jpg 1024w, https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/06\/Photo-Sarkan.jpg 1067w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14d56da elementor-widget elementor-widget-heading\" data-id=\"14d56da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Dott. Serkan Yavuz  <\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f4b2f9 elementor-widget elementor-widget-heading\" data-id=\"2f4b2f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Chirurgo dell'impianto di capelli<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-439a3ef elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"439a3ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3462dcb elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"3462dcb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Mzg3MTcsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">formazione ed esperienza<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2237718 elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2237718\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c205ad2\" data-id=\"c205ad2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-08c3208 elementor-widget elementor-widget-image\" data-id=\"08c3208\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"532\" src=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/07\/dentist-his-assistant-working-with-patient-dentist-chair-dentist-office-1024x681.jpg\" class=\"attachment-large size-large wp-image-38613\" alt=\"\" srcset=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/07\/dentist-his-assistant-working-with-patient-dentist-chair-dentist-office-1024x681.jpg 1024w, https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/07\/dentist-his-assistant-working-with-patient-dentist-chair-dentist-office-300x200.jpg 300w, https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/07\/dentist-his-assistant-working-with-patient-dentist-chair-dentist-office-768x511.jpg 768w, https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/07\/dentist-his-assistant-working-with-patient-dentist-chair-dentist-office-1536x1022.jpg 1536w, https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/07\/dentist-his-assistant-working-with-patient-dentist-chair-dentist-office-2048x1363.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-efc47b5 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"efc47b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/operation-des-dents\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Operazioni sui denti<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-172f0fc\" data-id=\"172f0fc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36ed9ce elementor-widget elementor-widget-heading\" data-id=\"36ed9ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Testimonianza<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db6cebf elementor-widget elementor-widget-heading\" data-id=\"db6cebf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Corinne Ang\u00e9lique Clerc  <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c092145 elementor-widget elementor-widget-text-editor\" data-id=\"c092145\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dal Natale 2021, dopo il covid, ho avuto un raffreddore costante. Nel gennaio 2022 ho iniziato ad avere dolori frequenti, emicranie terribili. Sono andata dal mio medico che mi ha dato delle medicine per curare il raffreddore, ma non hanno funzionato. Questa situazione \u00e8 andata avanti per cos\u00ec tanto tempo che abbiamo preso in considerazione tutto, compresi i pollini e le allergie causate dagli acari della polvere o dalla muffa nel mio appartamento.   <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4b6162 elementor-widget elementor-widget-accordion\" data-id=\"d4b6162\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2231\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2231\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Per saperne di pi\u00f9<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2231\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2231\"><p>Poi in aprile, improvvisamente, senza alcun dolore, ho perso un dente. Cos\u00ec sono andato dal mio dentista abituale. Mi ha fatto una visita di controllo e mi ha detto che i miei denti stavano iniziando ad allentarsi e che avevo bisogno di 1 o addirittura 2 impianti per sostituire alcuni dei miei denti. Mi ha fatto un preventivo di 12.000 franchi per sostituire 4 denti anteriori. Di conseguenza, ho notato che a volte il mio respiro era forte alla fine della giornata, il che era molto spiacevole per chi mi stava intorno e per me stesso. Ho deciso di rivolgermi a un secondo dentista nella vicina Francia per vedere se potevo ridurre il conto. Nel frattempo avevo lasciato passare un mese. Il dentista mi ha fatto molte domande sui miei genitori e sulla mia famiglia, per sapere se qualcuno di loro avesse avuto problemi ai denti in giovane et\u00e0, cosa che non \u00e8 avvenuta. L\u00ec mi disse che i miei denti erano appesi a un filo. Che i miei seni paranasali e la mascella superiore erano quasi inesistenti a causa di una malattia genetica. \u00c8 stato uno shock enorme!            <\/p>\n<p>Mi ha fatto capire che solo i miei denti sul lato destro dell&#8217;arcata inferiore erano adatti a reggere e mi ha fatto un preventivo di 24.000 euro che comprendeva l&#8217;estrazione di tutti i denti (tranne quelli sani) e l&#8217;installazione di 12 impianti. Il trattamento doveva essere effettuato nell&#8217;arco di 18 mesi, recandosi regolarmente a 2 ore di distanza da casa mia.   <\/p>\n<p>Due settimane dopo, mi \u00e8 stato presentato Sublime Clinique. Amor mi ha dato ottimi consigli, \u00e8 stato in grado di sentire l&#8217;urgenza della situazione e ha lottato con i medici per ottenere un consulto molto rapidamente e mi ha rassicurato sulla qualit\u00e0 delle cliniche che lavorano con lui. La sua attenzione, la sua empatia e la sua motivazione hanno fatto s\u00ec che pochi giorni dopo volassimo entrambi a Istanbul con un preventivo della clinica, che comprendeva la trasformazione della mia intera bocca e non solo di \u00be come proposto dal dentista francese, ma anche il costo del trasporto di lusso fino al sito e il pernottamento in un hotel di alto livello.    <\/p>\n<p>Quando sono arrivata, il consulto era stato fissato per una domenica, e i traduttori erano disponibili affinch\u00e9 potessi comunicare perfettamente in inglese e francese con il chirurgo dentale. Mi \u00e8 stato poi spiegato che un batterio aveva corroso la mia carne e che dovevo agire il pi\u00f9 rapidamente possibile, poich\u00e9 il danno era progredito nell&#8217;arco di due settimane. Poi sono crollato. L&#8217;intera \u00e9quipe della Clinica Sublime \u00e8 stata presente per sostenermi e darmi un momento per valutare la situazione e prendere una decisione. Mi hanno fatto capire che, anche se sarebbe stata una grande prova, dovevo agire rapidamente e prendermi cura della mia salute. Le mie paure sulla mia vita privata e sul modo in cui la gente mi guardava mi bloccavano, dover vivere senza denti per diversi mesi era un&#8217;idea insormontabile per me. Hanno saputo trovare le parole e i gesti per convincermi dell&#8217;importanza e dell&#8217;urgenza della situazione. Che la priorit\u00e0 fosse la mia salute e non il mio aspetto per qualche mese. Cos\u00ec ho accettato di sottopormi subito all&#8217;intervento, 30 minuti dopo era tutto pronto.          <\/p>\n<p>Prima, dopo l&#8217;operazione e al mio ritorno in Svizzera, l&#8217;intero team \u00e8 stato straordinario. Il loro sostegno durante questa prova \u00e8 stato fondamentale e mi ha dato una forza interiore che non sapevo di avere.   <\/p><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1fa414a elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1fa414a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8c1c95b\" data-id=\"8c1c95b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6bf23bf elementor-widget elementor-widget-heading\" data-id=\"6bf23bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Contatto<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2da564 elementor-widget elementor-widget-heading\" data-id=\"c2da564\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contattateci<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2fc8cb elementor-widget elementor-widget-text-editor\" data-id=\"f2fc8cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sognate di sentirvi meglio nel vostro corpo e di godere delle ricchezze culturali di un paese straordinario&nbsp;?<\/p>\n<p>Contattateci e realizzate il vostro sogno.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f407198 elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"f407198\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/sublime-clinic.ch\/it\/contatto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contattateci<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3c3a047\" data-id=\"3c3a047\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f7fcb2 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"5f7fcb2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Modulo di contatto<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-064c1cc elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"064c1cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Avanti&quot;,&quot;step_previous_label&quot;:&quot;Precedente&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Nuovo modulo\" aria-label=\"Nuovo modulo\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"38620\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"064c1cc\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Le nostre cliniche partner - Clinica specialistica Sublime\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"38620\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tNome\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nome *\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_7679ec1 elementor-col-50\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_7679ec1\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tNome\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_7679ec1]\" id=\"form-field-field_7679ec1\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nome\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-email elementor-col-50\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tTelefono\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Telefono\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Sono accettati solo numeri e caratteri telefonici (#, -, *, ecc.).\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-field_905751a elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_905751a\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[field_905751a]\" id=\"form-field-field_905751a\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Email *\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tMessaggio\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" placeholder=\"Messaggio\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha_v3 elementor-field-group elementor-column elementor-field-group-field_4442083 elementor-col-100 recaptcha_v3-bottomright\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-field_4442083\"><div class=\"elementor-g-recaptcha\" data-sitekey=\"6Ld65bofAAAAAG3rwzBMLtr0H5srIXj6lzjDn-fw\" data-type=\"v3\" data-action=\"Form\" data-badge=\"bottomright\" data-size=\"invisible\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Inviare<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>I nostri interventi Contatto Cliniche Le nostre cliniche partner In qualit\u00e0 di azienda svizzera specializzata in turismo medico, collaboriamo in esclusiva con due delle cliniche pi\u00f9 rinomate della Turchia. Con oltre 55.000 metri quadrati di spazio interno, il nostro ospedale partner \u00e8 alto 19 piani e pu\u00f2 ospitare 450 letti. Tra le 16 sale operatorie [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-38620","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le nostre cliniche partner - Clinica specialistica Sublime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sublime-clinic.ch\/it\/clinica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le nostre cliniche partner - Clinica specialistica Sublime\" \/>\n<meta property=\"og:description\" content=\"I nostri interventi Contatto Cliniche Le nostre cliniche partner In qualit\u00e0 di azienda svizzera specializzata in turismo medico, collaboriamo in esclusiva con due delle cliniche pi\u00f9 rinomate della Turchia. Con oltre 55.000 metri quadrati di spazio interno, il nostro ospedale partner \u00e8 alto 19 piani e pu\u00f2 ospitare 450 letti. Tra le 16 sale operatorie [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sublime-clinic.ch\/it\/clinica\/\" \/>\n<meta property=\"og:site_name\" content=\"Sublime\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-23T11:52:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/elementor\/thumbs\/IMG_1003-pqqw1zd0mwdv2f9ie9be5nlj4kc35mtenltcx0u2tg.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sublime-clinic.ch\\\/it\\\/clinica\\\/\",\"url\":\"https:\\\/\\\/sublime-clinic.ch\\\/it\\\/clinica\\\/\",\"name\":\"Le nostre cliniche partner - Clinica specialistica Sublime\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sublime-clinic.ch\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sublime-clinic.ch\\\/it\\\/clinica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sublime-clinic.ch\\\/it\\\/clinica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sublime-clinic.ch\\\/wp-content\\\/uploads\\\/elementor\\\/thumbs\\\/IMG_1003-pqqw1zd0mwdv2f9ie9be5nlj4kc35mtenltcx0u2tg.jpg\",\"datePublished\":\"2023-01-10T09:48:41+00:00\",\"dateModified\":\"2026-06-23T11:52:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sublime-clinic.ch\\\/it\\\/clinica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sublime-clinic.ch\\\/it\\\/clinica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/sublime-clinic.ch\\\/it\\\/clinica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sublime-clinic.ch\\\/wp-content\\\/uploads\\\/elementor\\\/thumbs\\\/IMG_1003-pqqw1zd0mwdv2f9ie9be5nlj4kc35mtenltcx0u2tg.jpg\",\"contentUrl\":\"https:\\\/\\\/sublime-clinic.ch\\\/wp-content\\\/uploads\\\/elementor\\\/thumbs\\\/IMG_1003-pqqw1zd0mwdv2f9ie9be5nlj4kc35mtenltcx0u2tg.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sublime-clinic.ch\\\/it\\\/clinica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sublime-clinic.ch\\\/it\\\/accoglienza\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le nostre cliniche partner\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sublime-clinic.ch\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/sublime-clinic.ch\\\/it\\\/\",\"name\":\"Sublime\",\"description\":\"Specialist Clinic\",\"publisher\":{\"@id\":\"https:\\\/\\\/sublime-clinic.ch\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sublime-clinic.ch\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sublime-clinic.ch\\\/it\\\/#organization\",\"name\":\"Sublime Clinic\",\"url\":\"https:\\\/\\\/sublime-clinic.ch\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/sublime-clinic.ch\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sublime-clinic.ch\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logo-sublime-clinic.png\",\"contentUrl\":\"https:\\\/\\\/sublime-clinic.ch\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logo-sublime-clinic.png\",\"width\":900,\"height\":794,\"caption\":\"Sublime Clinic\"},\"image\":{\"@id\":\"https:\\\/\\\/sublime-clinic.ch\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le nostre cliniche partner - Clinica specialistica Sublime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sublime-clinic.ch\/it\/clinica\/","og_locale":"it_IT","og_type":"article","og_title":"Le nostre cliniche partner - Clinica specialistica Sublime","og_description":"I nostri interventi Contatto Cliniche Le nostre cliniche partner In qualit\u00e0 di azienda svizzera specializzata in turismo medico, collaboriamo in esclusiva con due delle cliniche pi\u00f9 rinomate della Turchia. Con oltre 55.000 metri quadrati di spazio interno, il nostro ospedale partner \u00e8 alto 19 piani e pu\u00f2 ospitare 450 letti. Tra le 16 sale operatorie [&hellip;]","og_url":"https:\/\/sublime-clinic.ch\/it\/clinica\/","og_site_name":"Sublime","article_modified_time":"2026-06-23T11:52:10+00:00","og_image":[{"url":"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/elementor\/thumbs\/IMG_1003-pqqw1zd0mwdv2f9ie9be5nlj4kc35mtenltcx0u2tg.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sublime-clinic.ch\/it\/clinica\/","url":"https:\/\/sublime-clinic.ch\/it\/clinica\/","name":"Le nostre cliniche partner - Clinica specialistica Sublime","isPartOf":{"@id":"https:\/\/sublime-clinic.ch\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sublime-clinic.ch\/it\/clinica\/#primaryimage"},"image":{"@id":"https:\/\/sublime-clinic.ch\/it\/clinica\/#primaryimage"},"thumbnailUrl":"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/elementor\/thumbs\/IMG_1003-pqqw1zd0mwdv2f9ie9be5nlj4kc35mtenltcx0u2tg.jpg","datePublished":"2023-01-10T09:48:41+00:00","dateModified":"2026-06-23T11:52:10+00:00","breadcrumb":{"@id":"https:\/\/sublime-clinic.ch\/it\/clinica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sublime-clinic.ch\/it\/clinica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/sublime-clinic.ch\/it\/clinica\/#primaryimage","url":"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/elementor\/thumbs\/IMG_1003-pqqw1zd0mwdv2f9ie9be5nlj4kc35mtenltcx0u2tg.jpg","contentUrl":"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/elementor\/thumbs\/IMG_1003-pqqw1zd0mwdv2f9ie9be5nlj4kc35mtenltcx0u2tg.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/sublime-clinic.ch\/it\/clinica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sublime-clinic.ch\/it\/accoglienza\/"},{"@type":"ListItem","position":2,"name":"Le nostre cliniche partner"}]},{"@type":"WebSite","@id":"https:\/\/sublime-clinic.ch\/it\/#website","url":"https:\/\/sublime-clinic.ch\/it\/","name":"Sublime","description":"Specialist Clinic","publisher":{"@id":"https:\/\/sublime-clinic.ch\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sublime-clinic.ch\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/sublime-clinic.ch\/it\/#organization","name":"Sublime Clinic","url":"https:\/\/sublime-clinic.ch\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/sublime-clinic.ch\/it\/#\/schema\/logo\/image\/","url":"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/06\/logo-sublime-clinic.png","contentUrl":"https:\/\/sublime-clinic.ch\/wp-content\/uploads\/2022\/06\/logo-sublime-clinic.png","width":900,"height":794,"caption":"Sublime Clinic"},"image":{"@id":"https:\/\/sublime-clinic.ch\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sublime-clinic.ch\/it\/wp-json\/wp\/v2\/pages\/38620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sublime-clinic.ch\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sublime-clinic.ch\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sublime-clinic.ch\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sublime-clinic.ch\/it\/wp-json\/wp\/v2\/comments?post=38620"}],"version-history":[{"count":5,"href":"https:\/\/sublime-clinic.ch\/it\/wp-json\/wp\/v2\/pages\/38620\/revisions"}],"predecessor-version":[{"id":46127,"href":"https:\/\/sublime-clinic.ch\/it\/wp-json\/wp\/v2\/pages\/38620\/revisions\/46127"}],"wp:attachment":[{"href":"https:\/\/sublime-clinic.ch\/it\/wp-json\/wp\/v2\/media?parent=38620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}